{"id":4844,"date":"2024-03-28T09:31:24","date_gmt":"2024-03-28T09:31:24","guid":{"rendered":"https:\/\/www.cocinasdiseno.com\/muebles-a-medida\/"},"modified":"2024-08-30T12:16:02","modified_gmt":"2024-08-30T12:16:02","slug":"meubels-op-maat","status":"publish","type":"page","link":"https:\/\/www.cocinasdiseno.com\/nl\/meubels-op-maat\/","title":{"rendered":"Meubels op maat"},"content":{"rendered":"\n<div class=\"wp-block-harington-gutenberg-container content-row light-section full row_padding_top row_padding_bottom row_padding_left row_padding_right change-header-color\" data-bgcolor=\"#eeeeee\" style=\"text-align:left\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h6 class=\"wp-block-heading has-mask\">\/ MEER DAN 20 JAAR CRE\u00cbREN VAN DROOMRUIMTES<\/h6>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr><hr>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h5 class=\"wp-block-heading has-mask\">Maatwerk voor uw huis: meubels op maat die uw stijl weerspiegelen<\/h5>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Bij <em>Cocinas Dise\u00f1o Costablanca<\/em> begrijpen we dat elk huis uniek is, en daarom bieden we op maat gemaakte ontwerpdiensten om <strong>meubels op maat<\/strong> te cre\u00ebren die perfect aansluiten bij uw behoeften en levensstijl. Van keukens tot inbouwkasten en woonkamermeubels, ons team van experts werkt nauw met u samen om uw voorkeuren te begrijpen en oplossingen te cre\u00ebren die uw ruimte transformeren in iets echt bijzonders.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-harington-gutenberg-container content-row dark-section full row_padding_top row_padding_left row_padding_right\" data-bgcolor=\"#171717\" style=\"text-align:left\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<hr>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-x-large-font-size\" style=\"font-style:normal;font-weight:700\">KWALITEIT EN DUURZAAMHEID: ZORGVULDIG GESELECTEERDE MATERIALEN VOOR UW MEUBELS OP MAAT<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">We zijn er trots op dat we met de beste beschikbare materialen op de markt werken om de kwaliteit en duurzaamheid van uw <strong>meubels op maat<\/strong> te garanderen. Van edele houtsoorten tot hoogwaardige laminaten, we selecteren elk materiaal zorgvuldig om ervoor te zorgen dat uw meubels niet alleen visueel indrukwekkend zijn, maar ook functioneel en bestand tegen de tand des tijds. Ons streven naar uitmuntendheid komt tot uiting in elk detail, van de keuze van het beslag tot de uiteindelijke afwerking, om ervoor te zorgen dat uw op maat gemaakte meubels een investering zijn waarvan u jarenlang zult genieten.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns are-vertically-aligned-bottom is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-x-large-font-size\" style=\"font-style:normal;font-weight:700\">ERVARING EN PROFESSIONALITEIT: VERTROUW OP KEUKENONTWERP COSTABLANCA VOOR UW MEUBELS OP MAAT.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Met jarenlange ervaring in het ontwerp en de fabricage van <strong>meubels op maat<\/strong>, kunt u vertrouwen op <em>Cocinas Dise\u00f1o Costablanca<\/em> om oplossingen te bieden die uw verwachtingen overtreffen. Ons team van hooggekwalificeerde ambachtslieden zet zich in om een uitzonderlijke service te bieden, van het initi\u00eble concept tot de uiteindelijke installatie. Of u nu uw keuken wilt renoveren, een op maat gemaakte inloopkast wilt cre\u00ebren of meubels voor een andere ruimte in uw huis wilt ontwerpen, wij staan klaar om uw dromen werkelijkheid te maken. Vertrouw op ons om <strong>meubels op maat<\/strong> te cre\u00ebren die niet alleen functioneel en esthetisch aantrekkelijk zijn, maar ook een ware uitdrukking van uw stijl en persoonlijkheid.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"button-wrap small-btn right button-link \"><div class=\"icon-wrap parallax-wrap\"><div class=\"button-icon parallax-element\"><i class=\"fa-solid fa-arrow-right\"><\/i><\/div><\/div><a target=\"_blank\" href=\"https:\/\/www.cocinasdiseno.com\/nl\/contact\/\"><div class=\"button-text sticky right\"><span data-hover=\"Contact\">Contact<\/span><\/div><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-mask-fill has-small-font-size\"><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr>\n\n\n\n<div id=\"itemsWrapperLinks\"><div id=\"itemsWrapper\" class=\"scale-fitthumbs fx-two\"><!-- Portfolio Wrap --><div class=\"portfolio-wrap flex-grid content-full-width fade-scaleout-effect\"><!-- Portfolio Columns --><div class=\"portfolio portfolio-shortcode\"><div class=\"item trigger-item carpinteria estantes-y-muebles reforma \" data-color=\"#444444\"><div class=\"item-parallax\"><div class=\"item-appear\"><div class=\"item-content\"><a class=\"item-wrap ajax-link-project\" data-type=\"page-transition\" href=\"https:\/\/www.cocinasdiseno.com\/nl\/portfolio\/armarios-a-medida\/\"><\/a><div class=\"item-wrap-image\"><img decoding=\"async\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2919-copia.jpg\" class=\"item-image grid__item-img trigger-item-link\" alt=\"Armarios_a_medida_5\"><\/div><img decoding=\"async\" class=\"grid__item-img grid__item-img--large\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2919-copia.jpg\" alt=\"Armarios_a_medida_5\" \/><\/div><\/div><div class=\"item-caption-wrapper\"><div class=\"item-caption\"><div class=\"item-title\"><span>Armarios<\/span><span>a medida<\/span><\/div><div class=\"item-cat\"><span data-hover=\"Ver trabajo\">Carpinteria, Estantes y muebles, Reformas<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"item trigger-item banos carpinteria estantes-y-muebles reforma \" data-color=\"#444444\"><div class=\"item-parallax\"><div class=\"item-appear\"><div class=\"item-content\"><a class=\"item-wrap ajax-link-project\" data-type=\"page-transition\" href=\"https:\/\/www.cocinasdiseno.com\/nl\/portfolio\/bano-moderno-2\/\"><\/a><div class=\"item-wrap-image\"><img decoding=\"async\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2937.jpg\" class=\"item-image grid__item-img trigger-item-link\" alt=\"Reforma_ba\u00f1o_2\"><\/div><img decoding=\"async\" class=\"grid__item-img grid__item-img--large\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2937.jpg\" alt=\"Reforma_ba\u00f1o_2\" \/><\/div><\/div><div class=\"item-caption-wrapper\"><div class=\"item-caption\"><div class=\"item-title\"><span>Ba\u00f1o<\/span><span>moderno<\/span><\/div><div class=\"item-cat\"><span data-hover=\"Ver trabajo\">Ba\u00f1os, Carpinteria, Estantes y muebles, Reformas<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"item trigger-item banos carpinteria estantes-y-muebles reforma \" data-color=\"#444444\"><div class=\"item-parallax\"><div class=\"item-appear\"><div class=\"item-content\"><a class=\"item-wrap ajax-link-project\" data-type=\"page-transition\" href=\"https:\/\/www.cocinasdiseno.com\/nl\/portfolio\/bano-moderno\/\"><\/a><div class=\"item-wrap-image\"><img decoding=\"async\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2929.jpg\" class=\"item-image grid__item-img trigger-item-link\" alt=\"Ba\u00f1o_moderno_5\"><\/div><img decoding=\"async\" class=\"grid__item-img grid__item-img--large\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2929.jpg\" alt=\"Ba\u00f1o_moderno_5\" \/><\/div><\/div><div class=\"item-caption-wrapper\"><div class=\"item-caption\"><div class=\"item-title\"><span>Ba\u00f1o<\/span><span>moderno gris<\/span><\/div><div class=\"item-cat\"><span data-hover=\"Ver trabajo\">Ba\u00f1os, Carpinteria, Estantes y muebles, Reformas<\/span><\/div><\/div><\/div><\/div><\/div><div class=\"item trigger-item carpinteria estantes-y-muebles reforma \" data-color=\"#444444\"><div class=\"item-parallax\"><div class=\"item-appear\"><div class=\"item-content\"><a class=\"item-wrap ajax-link-project\" data-type=\"page-transition\" href=\"https:\/\/www.cocinasdiseno.com\/nl\/portfolio\/zona-lavanderia\/\"><\/a><div class=\"item-wrap-image\"><img decoding=\"async\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2947.jpg\" class=\"item-image grid__item-img trigger-item-link\" alt=\"zona_lavander\u00eda_5\"><\/div><img decoding=\"async\" class=\"grid__item-img grid__item-img--large\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/05\/IMG_2947.jpg\" alt=\"zona_lavander\u00eda_5\" \/><\/div><\/div><div class=\"item-caption-wrapper\"><div class=\"item-caption\"><div class=\"item-title\"><span>Zona<\/span><span>Lavander\u00eda<\/span><\/div><div class=\"item-cat\"><span data-hover=\"Ver trabajo\">Carpinteria, Estantes y muebles, Reformas<\/span><\/div><\/div><\/div><\/div><\/div><\/div><!--\/Portfolio Columns--><\/div><!--\/Portfolio Wrap--><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-harington-gutenberg-container content-row light-section full row_padding_top row_padding_left row_padding_right change-header-color nosotros-porque\" data-bgcolor=\"#ffffff\" style=\"text-align:left\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-mask no-margins\">Onze merken<\/h2>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-mask no-margins has-medium-font-size\">HUISHOUDELIJKE APPARATEN<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1187\" height=\"542\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FABER.png\" alt=\"\" class=\"wp-image-3660\" style=\"width:160px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FABER.png 1187w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FABER-300x137.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FABER-1024x468.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FABER-768x351.png 768w\" sizes=\"auto, (max-width: 1187px) 100vw, 1187px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"174\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/elica-s-p-a-logo-vector.png\" alt=\"\" class=\"wp-image-3661\" style=\"width:120px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/elica-s-p-a-logo-vector.png 500w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/elica-s-p-a-logo-vector-300x104.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"486\" height=\"76\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/simens.png\" alt=\"\" class=\"wp-image-3289\" style=\"width:160px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/simens.png 486w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/simens-300x47.png 300w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"420\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/2021_Whirlpool_Corp_1C_Black_RGB.png\" alt=\"\" class=\"wp-image-3662\" style=\"width:120px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/2021_Whirlpool_Corp_1C_Black_RGB.png 1260w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/2021_Whirlpool_Corp_1C_Black_RGB-300x100.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/2021_Whirlpool_Corp_1C_Black_RGB-1024x341.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/2021_Whirlpool_Corp_1C_Black_RGB-768x256.png 768w\" sizes=\"auto, (max-width: 1260px) 100vw, 1260px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"197\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Logo_Zanussi.png\" alt=\"\" class=\"wp-image-3663\" style=\"width:100px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Logo_Zanussi.png 730w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Logo_Zanussi-300x81.png 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/bosch_logo_icon_181287.png\" alt=\"\" class=\"wp-image-3664\" style=\"width:160px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/bosch_logo_icon_181287.png 512w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/bosch_logo_icon_181287-300x300.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/bosch_logo_icon_181287-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"272\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/17718901_logo-horizontal-azul-balay.png\" alt=\"\" class=\"wp-image-3665\" style=\"width:144px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/17718901_logo-horizontal-azul-balay.png 800w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/17718901_logo-horizontal-azul-balay-300x102.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/17718901_logo-horizontal-azul-balay-768x261.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"101\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/512px-Smeg_logo.png\" alt=\"\" class=\"wp-image-3666\" style=\"width:162px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/512px-Smeg_logo.png 512w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/512px-Smeg_logo-300x59.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image wp-duotone-unset-1\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/siemens-studioline-logo-300x150px.png\" alt=\"\" class=\"wp-image-3668\" style=\"width:157px;height:auto\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"320\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl.png\" alt=\"\" class=\"wp-image-3669\" style=\"width:160px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl.png 2560w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl-300x37.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl-1024x128.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl-768x96.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl-1536x192.png 1536w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_ci_liebherr_fl-2048x256.png 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1594\" height=\"425\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/DeDietrichLogo.png\" alt=\"\" class=\"wp-image-3670\" style=\"width:178px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/DeDietrichLogo.png 1594w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/DeDietrichLogo-300x80.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/DeDietrichLogo-1024x273.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/DeDietrichLogo-768x205.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/DeDietrichLogo-1536x410.png 1536w\" sizes=\"auto, (max-width: 1594px) 100vw, 1594px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2280\" height=\"1307\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8.png\" alt=\"\" class=\"wp-image-3671\" style=\"width:100px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8.png 2280w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8-300x172.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8-1024x587.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8-768x440.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8-1536x881.png 1536w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/TEKA-8-2048x1174.png 2048w\" sizes=\"auto, (max-width: 2280px) 100vw, 2280px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/falmec.webp\" alt=\"\" class=\"wp-image-3672\" style=\"width:146px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/falmec.webp 1080w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/falmec-300x300.webp 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/falmec-1024x1024.webp 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/falmec-150x150.webp 150w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/falmec-768x768.webp 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"843\" height=\"159\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_nodor_rojo.png\" alt=\"\" class=\"wp-image-3673\" style=\"width:120px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_nodor_rojo.png 843w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_nodor_rojo-300x57.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/logo_nodor_rojo-768x145.png 768w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"65\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FRECAN.png\" alt=\"\" class=\"wp-image-3674\" style=\"width:140px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FRECAN.png 450w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/FRECAN-300x43.png 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-mask no-margins has-medium-font-size\">GOOTSTENEN EN KRANEN<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg.png\" alt=\"\" class=\"wp-image-3675\" style=\"width:160px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg.png 2560w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg-300x169.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg-1024x576.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg-768x432.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg-1536x864.png 1536w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/csm_Pressemitteilung_BORA-Facts-and-figures_80c3c74e0c.jpg-2048x1152.png 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"138\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/quooker.png\" alt=\"\" class=\"wp-image-3676\" style=\"width:142px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/quooker.png 366w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/quooker-300x113.png 300w\" sizes=\"auto, (max-width: 366px) 100vw, 366px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"124\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/luisina.png\" alt=\"\" class=\"wp-image-3286\" style=\"width:142px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/luisina.png 480w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/luisina-300x78.png 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"172\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/interbany.png\" alt=\"\" class=\"wp-image-3285\" style=\"width:112px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/interbany.png 440w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/11\/interbany-300x117.png 300w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"76\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/blanco.png\" alt=\"\" class=\"wp-image-3677\" style=\"width:120px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/blanco.png 400w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/blanco-300x57.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1574\" height=\"669\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Grohe-logo.png\" alt=\"\" class=\"wp-image-3678\" style=\"width:142px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Grohe-logo.png 1574w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Grohe-logo-300x128.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Grohe-logo-1024x435.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Grohe-logo-768x326.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Grohe-logo-1536x653.png 1536w\" sizes=\"auto, (max-width: 1574px) 100vw, 1574px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"300\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/franke.png\" alt=\"\" class=\"wp-image-3679\" style=\"width:162px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/franke.png 500w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/franke-300x180.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1.png\" alt=\"\" class=\"wp-image-3680\" style=\"width:144px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1.png 2560w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1-300x300.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1-1024x1024.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1-150x150.png 150w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1-768x768.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1-1536x1536.png 1536w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/plados_tras-1024x1024-1-2048x2048.png 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-mask no-margins has-medium-font-size\">KEUKENWERKBLADEN<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"86\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/silestone-logo.png\" alt=\"\" class=\"wp-image-3685\" style=\"width:158px;height:auto\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"500\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/sensa-by-cosentino-logo-vector.png\" alt=\"\" class=\"wp-image-3684\" style=\"width:134px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/sensa-by-cosentino-logo-vector.png 900w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/sensa-by-cosentino-logo-vector-300x167.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/sensa-by-cosentino-logo-vector-768x427.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"102\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Dekton-8.png\" alt=\"\" class=\"wp-image-3686\" style=\"width:173px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Dekton-8.png 384w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Dekton-8-300x80.png 300w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1139\" height=\"323\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/hi-macs.png\" alt=\"\" class=\"wp-image-3687\" style=\"width:158px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/hi-macs.png 1139w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/hi-macs-300x85.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/hi-macs-1024x290.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/hi-macs-768x218.png 768w\" sizes=\"auto, (max-width: 1139px) 100vw, 1139px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"937\" height=\"678\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Corian-Solid-Surface-logo-copia.png\" alt=\"\" class=\"wp-image-3688\" style=\"width:120px\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Corian-Solid-Surface-logo-copia.png 937w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Corian-Solid-Surface-logo-copia-300x217.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Corian-Solid-Surface-logo-copia-768x556.png 768w\" sizes=\"auto, (max-width: 937px) 100vw, 937px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h3 class=\"wp-block-heading has-text-align-center has-mask no-margins has-medium-font-size\">GROND<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"112\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/QUICK-STEP-8.png\" alt=\"\" class=\"wp-image-3689\" style=\"width:109px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/QUICK-STEP-8.png 370w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/QUICK-STEP-8-300x91.png 300w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/PARADOR.png\" alt=\"\" class=\"wp-image-3690\" style=\"width:157px;height:auto\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"377\" height=\"134\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/haro.png\" alt=\"\" class=\"wp-image-3693\" style=\"width:113px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/haro.png 377w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/haro-300x107.png 300w\" sizes=\"auto, (max-width: 377px) 100vw, 377px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Egger-Symbol-700x394-1.png\" alt=\"\" class=\"wp-image-3694\" style=\"width:108px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Egger-Symbol-700x394-1.png 700w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/Egger-Symbol-700x394-1-300x169.png 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<h3 class=\"wp-block-heading has-text-align-center has-mask no-margins has-medium-font-size\">VULT THUIS AAN<\/h3>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"272\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/CAUXI-1024x272.png\" alt=\"\" class=\"wp-image-3700\" style=\"width:83px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/CAUXI-1024x272.png 1024w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/CAUXI-300x80.png 300w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/CAUXI-768x204.png 768w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/CAUXI.png 1270w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"141\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/BAILEN.png\" alt=\"\" class=\"wp-image-3702\" style=\"width:72px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/BAILEN.png 350w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/BAILEN-300x121.png 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"47259\" height=\"10300\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/cancio-logo-svg-01.png\" alt=\"\" class=\"wp-image-3701\"\/><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<h3 class=\"wp-block-heading has-text-align-center has-mask no-margins has-medium-font-size\">BADKAMERMEUBELS<\/h3>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"332\" height=\"141\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/salgar.png\" alt=\"\" class=\"wp-image-3764\" style=\"width:78px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/salgar.png 332w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2024\/03\/salgar-300x127.png 300w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"332\" height=\"141\" src=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/10\/roca.png\" alt=\"\" class=\"wp-image-3101\" style=\"width:74px;height:auto\" srcset=\"https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/10\/roca.png 332w, https:\/\/www.cocinasdiseno.com\/wp-content\/uploads\/2023\/10\/roca-300x127.png 300w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-harington-gutenberg-container content-row light-section normal row_padding_top row_padding_bottom change-header-color\" data-bgcolor=\"#ffffff\" style=\"text-align:left\">\n<div class=\"title-moving-outer \"><h1 class=\"title-moving-forward\">Wereldwijd vertrouwen meer dan 500 klanten op ons.<\/h1><\/div>\n\n\n\n<div class=\"title-moving-outer \"><h1 class=\"title-moving-backward\">Wereldwijd vertrouwen meer dan 500 klanten op ons.<\/h1><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-harington-gutenberg-container content-row light-section full row_padding_top row_padding_bottom row_padding_left row_padding_right change-header-color\" data-bgcolor=\"#eeeeee\" style=\"text-align:center\">\n<hr>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">VRAAG EEN GRATIS OFFERTE AAN<\/h1>\n\n\n\n<hr><hr>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h5 class=\"wp-block-heading has-mask-fill has-black-color has-text-color\">Zullen we eens praten?<\/h5>\n\n\n\n<p class=\"has-text-align-center has-animation has-black-color has-text-color wp-block-paragraph\">Wij bieden je de beste aandacht en begeleiding voor je nieuwe project met alle enthousiasme en betrokkenheid die je verdient.<\/p>\n\n\n\n<hr>\n\n\n\n<div class=\"button-box has-animation \" data-delay=\"150\"><div class=\"clapat-button-wrap parallax-wrap hide-ball\"><div class=\"clapat-button parallax-element\"><div class=\"button-border parallax-element-second rounded\"><a class=\"\" href=\"https:\/\/cocinasdiseno.com\/nl\/contact\" target=\"_blank\"><span data-hover=\"Contact\">Contact<\/span><\/a><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-4844","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/pages\/4844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/comments?post=4844"}],"version-history":[{"count":3,"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/pages\/4844\/revisions"}],"predecessor-version":[{"id":4976,"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/pages\/4844\/revisions\/4976"}],"wp:attachment":[{"href":"https:\/\/www.cocinasdiseno.com\/nl\/wp-json\/wp\/v2\/media?parent=4844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}